{"id":823,"date":"2025-02-21T16:42:57","date_gmt":"2025-02-21T19:42:57","guid":{"rendered":"http:\/\/www.femasantarosa.com.br\/radio\/?p=823"},"modified":"2025-02-21T16:50:54","modified_gmt":"2025-02-21T19:50:54","slug":"psicologia-na-fema","status":"publish","type":"post","link":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/2025\/02\/21\/psicologia-na-fema\/","title":{"rendered":"PSICOLOGIA NA FEMA"},"content":{"rendered":"\n<p><strong>Novo curso APROVADO e tem CONCEITO 5 no MEC&nbsp;<\/strong><\/p>\n\n\n\n<p>As Faculdades FEMA anuncia seu mais novo curso superior, Psicologia, que foi autorizado com nota m\u00e1xima (5) pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC) que j\u00e1 ter\u00e1 a primeira turma no primeiro semestre de 2025. &nbsp;As inscri\u00e7\u00f5es para o Vestibular de Ver\u00e3o estar\u00e3o abertas a partir de setembro.<br>Antonio Roberto Lausmann Ternes, diretor das Faculdades FEMA, ressalta que o conceito m\u00e1ximo de autoriza\u00e7\u00e3o atesta n\u00e3o apenas a excel\u00eancia das condi\u00e7\u00f5es de ensino e do corpo docente da Institui\u00e7\u00e3o, mas tamb\u00e9m a ades\u00e3o aos mais elevados padr\u00f5es de qualidade. E que se trata de uma conquista que reflete o reconhecimento de um trabalho dedicado e de uma equipe comprometida. Atualmente, as Faculdades FEMA oferecem os cursos de Administra\u00e7\u00e3o, Ci\u00eancias Cont\u00e1beis, Direito, Enfermagem e Marketing.<\/p>\n\n\n\n<p><strong>COORDENA\u00c7\u00c3O DO CURSO DE PSICOLOGIA<\/strong><\/p>\n\n\n\n<p>Juliane Colpo, psic\u00f3loga docente das Faculdades FEMA que coordena o N\u00facleo de Apoio Psicopedag\u00f3gico (NAP), c\u00e9lula da Institui\u00e7\u00e3o que atende em todos os n\u00edveis de forma\u00e7\u00e3o, \u00e9 a Coordenadora do novo curso de Psicologia. Ela comemora a conquista e ressalta: \u201cestamos orgulhosos da conquista do conceito 5 pelo Minist\u00e9rio da Educa\u00e7\u00e3o para o Curso de Psicologia, com a certeza da oferta de um curso de excel\u00eancia. O Curso de Psicologia da FEMA estar\u00e1 comprometido com a forma\u00e7\u00e3o integral dos estudantes, preparando-os para o desenvolvimento e exerc\u00edcio pleno de suas compet\u00eancias, para enfrentar os desafios contempor\u00e2neos da profiss\u00e3o com empatia, discernimento e solu\u00e7\u00f5es inovadoras\u201d, diz.<\/p>\n\n\n\n<p>O Curso de Psicologia da FEMA \u00e9 focado na consolida\u00e7\u00e3o de uma forma\u00e7\u00e3o generalista human\u00edstica, promovendo uma an\u00e1lise cr\u00edtica da Psicologia e da realidade social. Seu objetivo \u00e9 capacitar os alunos para uma atua\u00e7\u00e3o profissional qualificada em diversos contextos, impactando indiv\u00edduos, coletividades e organiza\u00e7\u00f5es.<\/p>\n\n\n\n<p>Em entrevista \u00e0 R\u00e1dio FEMA, manh\u00e3 dessa ter\u00e7a-feira (11\/jun), Juliane Colpo ressaltou pontos importantes da conquista, al\u00e9m da felicidade de poder anunciar oficialmente a disponibilidade do curso j\u00e1 para o pr\u00f3ximo processo seletivo, o vestibular de ver\u00e3o.<\/p>\n\n\n\n<p>Sobre o processo, explicou que foi uma grande demanda que contou com a dedica\u00e7\u00e3o intensa da equipe desde a elabora\u00e7\u00e3o do projeto pedag\u00f3gico, o estudo das peculiaridades da nossa regi\u00e3o, o di\u00e1logo com gestores de v\u00e1rias institui\u00e7\u00f5es ligadas ao processo; possibilitando o alinhamento das principais diretrizes. \u201cuma caminhada respons\u00e1vel e comprometida com o que tem de mais significativo, no que tange a ci\u00eancia da psicologia. Para n\u00f3s \u00e9 de extrema relev\u00e2ncia, pois, j\u00e1 somos reconhecidos na Gradua\u00e7\u00e3o em Sa\u00fade, e tudo foi e \u00e9 pensado na transforma\u00e7\u00e3o das pessoas que estudam na FEMA, para que transformem a realidade onde atuar\u00e3o nas diferentes frentes. O conceito m\u00e1ximo mostra que temos legitimidade para estarmos nesse lugar, assumindo o compromisso de formar pessoas, sujeitos trabalhadores para uma atua\u00e7\u00e3o humana, integral &#8230;\u201d.<\/p>\n\n\n\n<p>Juliane Colpo tamb\u00e9m destacou o foco da forma\u00e7\u00e3o, que vem sendo estruturada desde o per\u00edodo da pandemia da Covid-19.<\/p>\n\n\n\n<p>\u201cA FEMA j\u00e1 vem trazendo um a abordagem do manejo das crises, de desastres, quest\u00f5es sociais que apresentam demandam extremas&#8230;situa\u00e7\u00f5es emergenciais de alta gravidade e complexidade. E nosso curso de Psicologia tem, tamb\u00e9m, o olhar voltado para quest\u00f5es como essas de forma aprofundada. Sem contar que \u00e9 grande a caminhada da FEMA no desenvolvimento de um trabalho relacionado ao ser humano na sua integridade\u201d.<\/p>\n\n\n\n<p>Acompanhe a programa\u00e7\u00e3o da R\u00e1dio FEMA para informa\u00e7\u00f5es ainda mais aprofundadas sobre o nosso Curso das Faculdades FEMA e sobre o universo da Educa\u00e7\u00e3o como um todo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"784\" src=\"http:\/\/www.femasantarosa.com.br\/radio\/wp-content\/uploads\/2025\/02\/image-1024x784.png\" alt=\"\" class=\"wp-image-825\" srcset=\"https:\/\/www.femasantarosa.com.br\/radio\/wp-content\/uploads\/2025\/02\/image-1024x784.png 1024w, https:\/\/www.femasantarosa.com.br\/radio\/wp-content\/uploads\/2025\/02\/image-300x230.png 300w, https:\/\/www.femasantarosa.com.br\/radio\/wp-content\/uploads\/2025\/02\/image-768x588.png 768w, https:\/\/www.femasantarosa.com.br\/radio\/wp-content\/uploads\/2025\/02\/image.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Novo curso APROVADO e tem CONCEITO 5 no MEC&nbsp; As Faculdades FEMA anuncia seu mais novo curso superior, Psicologia, que foi autorizado com nota m\u00e1xima (5) pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC) que j\u00e1 ter\u00e1 a primeira turma no primeiro semestre de 2025. &nbsp;As inscri\u00e7\u00f5es para o Vestibular de Ver\u00e3o estar\u00e3o abertas a partir de setembro.Antonio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/wp-json\/wp\/v2\/posts\/823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/wp-json\/wp\/v2\/comments?post=823"}],"version-history":[{"count":1,"href":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/wp-json\/wp\/v2\/posts\/823\/revisions"}],"predecessor-version":[{"id":826,"href":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/wp-json\/wp\/v2\/posts\/823\/revisions\/826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/wp-json\/wp\/v2\/media\/829"}],"wp:attachment":[{"href":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/wp-json\/wp\/v2\/media?parent=823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/wp-json\/wp\/v2\/categories?post=823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.femasantarosa.com.br\/radio\/index.php\/wp-json\/wp\/v2\/tags?post=823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}